{"id":1650,"date":"2015-03-13T08:00:17","date_gmt":"2015-03-13T08:00:17","guid":{"rendered":"https:\/\/www.primecursos.com.br\/blog\/?p=1650"},"modified":"2015-03-09T18:30:48","modified_gmt":"2015-03-09T18:30:48","slug":"apoiando-filhos-estudos","status":"publish","type":"post","link":"https:\/\/www.primecursos.com.br\/blog\/apoiando-filhos-estudos\/","title":{"rendered":"Apoiando os filhos nos estudos"},"content":{"rendered":"<figure id=\"attachment_1653\" aria-describedby=\"caption-attachment-1653\" style=\"width: 620px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"wp-image-1653 size-prime-thumb-620\" title=\"Fam\u00edlia e educa\u00e7\u00e3o\" src=\"https:\/\/www.primecursos.com.br\/blog\/wp-content\/uploads\/2015\/03\/Pais-apoiando-educa\u00e7\u00e3o-620x300.jpg\" alt=\"Pais apoiando educa\u00e7\u00e3o\" width=\"620\" height=\"300\" \/><figcaption id=\"caption-attachment-1653\" class=\"wp-caption-text\">Apoiando os filhos nos estudos <br \/>Cr\u00e9ditos da Imagem: Cafnr\u00a0\u00a0 Via: Compfight<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">O suporte dos pais e a cria\u00e7\u00e3o de um bom conv\u00edvio familiar como extens\u00e3o da escola contribuem de forma significativa para o desenvolvimento educacional das crian\u00e7as. Quando os respons\u00e1veis incentivam o aprendizado e compartilham da vida escolar, al\u00e9m de se alfabetizarem com mais facilidade, os filhos alcan\u00e7am notas melhores, permanecem por mais tempo no sistema de <a href=\"https:\/\/www.primecursos.com.br\/educacao\/\" target=\"_blank\"><strong>educa\u00e7\u00e3o<\/strong><\/a> e alcan\u00e7am renda superior na idade adulta.<\/p>\n<p style=\"text-align: justify;\">A fam\u00edlia pode prestar ajuda de diversas formas: conversando a respeito do cotidiano na escola (qual conte\u00fado foi trabalhado naquele dia, quais atividades foram executadas, projetos futuros etc.); participando das reuni\u00f5es escolares; verificando o caderno da crian\u00e7a frequentemente; e impedindo que o estudante deixe de ir \u00e0s aulas.<\/p>\n<p style=\"text-align: justify;\">\u00c9 importante que os pais estejam dispon\u00edveis para ajudar nas tarefas do col\u00e9gio sempre que poss\u00edvel e continuem fazendo isso nos n\u00edveis que se seguem ap\u00f3s a alfabetiza\u00e7\u00e3o. Ao sanar as d\u00favidas e ajudar a encontrar solu\u00e7\u00f5es, os adultos est\u00e3o mostrando \u00e0s crian\u00e7as o qu\u00e3o importante s\u00e3o os estudos e o qu\u00e3o eles se interessam por elas, fazendo que se sintam amadas e valorizadas.<\/p>\n<p style=\"text-align: justify;\">Muitos pais t\u00eam consci\u00eancia da seriedade que \u00e9 auxiliar os filhos no seu desenvolvimento educacional, mas se sentem inseguros em faz\u00ea-lo por j\u00e1 terem conclu\u00eddo os estudos h\u00e1 um determinado tempo. Nesses casos, a internet pode ser uma grande aliada e revelar boas alternativas de conte\u00fado, permitindo a revis\u00e3o de diferentes disciplinas.<\/p>\n<p style=\"text-align: justify;\">Por meio dela, \u00e9 poss\u00edvel ter acesso a diversos materiais, mas \u00e9 preciso estar atento \u00e0 confiabilidade das informa\u00e7\u00f5es. Um lugar seguro para estudantes e pais aprenderem e reverem regras, f\u00f3rmulas e conceitos das principais mat\u00e9rias escolares \u00e9 o site da <strong>Prime Cursos<\/strong>. Nele, est\u00e3o dispon\u00edveis <a href=\"https:\/\/www.primecursos.com.br\/cursos\/\" target=\"_blank\"><strong>cursos online<\/strong><\/a> com material rico e detalhado sobre matem\u00e1tica, qu\u00edmica, biologia, hist\u00f3ria, entre outras disciplinas. Confira, atualize-se, aprenda e ajude seu filho a desenvolver-se.<\/p>\n<h2>Como ajudar seu filho a ter sucesso na escola<\/h2>\n<p><iframe src=\"\/\/www.youtube.com\/embed\/nEJauApmnHU\" width=\"600\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p style=\"text-align: center;\">Cr\u00e9ditos Canal Youtube &#8211; Jornal Bom Dia Paran\u00e1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Filhos que contam com o incentivo dos pais em rela\u00e7\u00e3o a educa\u00e7\u00e3o, possuem mais chances de obter sucesso profissional no futuro.<\/p>\n","protected":false},"author":10,"featured_media":1653,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[],"tags":[13],"class_list":["post-1650","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-estudos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Apoiando os filhos nos estudos | Prime Cursos<\/title>\n<meta name=\"description\" content=\"Aprenda qual a melhor maneira de ajudar os filhos nos estudos, trazendo mais benef\u00edcios para o aprendizado das crian\u00e7as.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.primecursos.com.br\/blog\/apoiando-filhos-estudos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apoiando os filhos nos estudos | Prime Cursos\" \/>\n<meta property=\"og:description\" content=\"Aprenda qual a melhor maneira de ajudar os filhos nos estudos, trazendo mais benef\u00edcios para o aprendizado das crian\u00e7as.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.primecursos.com.br\/blog\/apoiando-filhos-estudos\/\" \/>\n<meta property=\"og:site_name\" content=\"Prime Cursos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/primecursos\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-13T08:00:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.primecursos.com.br\/blog\/wp-content\/uploads\/2015\/03\/Pais-apoiando-educa\u00e7\u00e3o.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"539\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bruno West\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bruno West\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/apoiando-filhos-estudos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/apoiando-filhos-estudos\\\/\"},\"author\":{\"name\":\"Bruno West\",\"@id\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/f75c3b4178ad1d2652ae372dc8284315\"},\"headline\":\"Apoiando os filhos nos estudos\",\"datePublished\":\"2015-03-13T08:00:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/apoiando-filhos-estudos\\\/\"},\"wordCount\":375,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/apoiando-filhos-estudos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/Pais-apoiando-educa\u00e7\u00e3o.jpg\",\"keywords\":[\"Estudos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/apoiando-filhos-estudos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/apoiando-filhos-estudos\\\/\",\"url\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/apoiando-filhos-estudos\\\/\",\"name\":\"Apoiando os filhos nos estudos | Prime Cursos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/apoiando-filhos-estudos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/apoiando-filhos-estudos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/Pais-apoiando-educa\u00e7\u00e3o.jpg\",\"datePublished\":\"2015-03-13T08:00:17+00:00\",\"description\":\"Aprenda qual a melhor maneira de ajudar os filhos nos estudos, trazendo mais benef\u00edcios para o aprendizado das crian\u00e7as.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/apoiando-filhos-estudos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/apoiando-filhos-estudos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/apoiando-filhos-estudos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/Pais-apoiando-educa\u00e7\u00e3o.jpg\",\"contentUrl\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/Pais-apoiando-educa\u00e7\u00e3o.jpg\",\"width\":1024,\"height\":539,\"caption\":\"Pais apoiando educa\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/apoiando-filhos-estudos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apoiando os filhos nos estudos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/\",\"name\":\"Prime Cursos\",\"description\":\"Cursos gr\u00e1tis com certificado v\u00e1lido\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/#organization\",\"name\":\"Prime Cursos Online\",\"url\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/prime-cursos-gratis-online-logo-070318b-1.png\",\"contentUrl\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/prime-cursos-gratis-online-logo-070318b-1.png\",\"width\":330,\"height\":80,\"caption\":\"Prime Cursos Online\"},\"image\":{\"@id\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/primecursos\\\/\",\"https:\\\/\\\/x.com\\\/primecursosbr\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/f75c3b4178ad1d2652ae372dc8284315\",\"name\":\"Bruno West\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3f4e7619846fa72d0a5106c7aebfc167807a00ac75982cb190722ab0a20b290b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3f4e7619846fa72d0a5106c7aebfc167807a00ac75982cb190722ab0a20b290b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3f4e7619846fa72d0a5106c7aebfc167807a00ac75982cb190722ab0a20b290b?s=96&d=mm&r=g\",\"caption\":\"Bruno West\"},\"sameAs\":[\"http:\\\/\\\/www.primecursos.com.br\"],\"url\":\"https:\\\/\\\/www.primecursos.com.br\\\/blog\\\/author\\\/bruno\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apoiando os filhos nos estudos | Prime Cursos","description":"Aprenda qual a melhor maneira de ajudar os filhos nos estudos, trazendo mais benef\u00edcios para o aprendizado das crian\u00e7as.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.primecursos.com.br\/blog\/apoiando-filhos-estudos\/","og_locale":"pt_BR","og_type":"article","og_title":"Apoiando os filhos nos estudos | Prime Cursos","og_description":"Aprenda qual a melhor maneira de ajudar os filhos nos estudos, trazendo mais benef\u00edcios para o aprendizado das crian\u00e7as.","og_url":"https:\/\/www.primecursos.com.br\/blog\/apoiando-filhos-estudos\/","og_site_name":"Prime Cursos","article_publisher":"https:\/\/www.facebook.com\/primecursos\/","article_published_time":"2015-03-13T08:00:17+00:00","og_image":[{"width":1024,"height":539,"url":"https:\/\/www.primecursos.com.br\/blog\/wp-content\/uploads\/2015\/03\/Pais-apoiando-educa\u00e7\u00e3o.jpg","type":"image\/jpeg"}],"author":"Bruno West","twitter_misc":{"Escrito por":"Bruno West","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.primecursos.com.br\/blog\/apoiando-filhos-estudos\/#article","isPartOf":{"@id":"https:\/\/www.primecursos.com.br\/blog\/apoiando-filhos-estudos\/"},"author":{"name":"Bruno West","@id":"https:\/\/www.primecursos.com.br\/blog\/#\/schema\/person\/f75c3b4178ad1d2652ae372dc8284315"},"headline":"Apoiando os filhos nos estudos","datePublished":"2015-03-13T08:00:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.primecursos.com.br\/blog\/apoiando-filhos-estudos\/"},"wordCount":375,"commentCount":3,"publisher":{"@id":"https:\/\/www.primecursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.primecursos.com.br\/blog\/apoiando-filhos-estudos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.primecursos.com.br\/blog\/wp-content\/uploads\/2015\/03\/Pais-apoiando-educa\u00e7\u00e3o.jpg","keywords":["Estudos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.primecursos.com.br\/blog\/apoiando-filhos-estudos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.primecursos.com.br\/blog\/apoiando-filhos-estudos\/","url":"https:\/\/www.primecursos.com.br\/blog\/apoiando-filhos-estudos\/","name":"Apoiando os filhos nos estudos | Prime Cursos","isPartOf":{"@id":"https:\/\/www.primecursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.primecursos.com.br\/blog\/apoiando-filhos-estudos\/#primaryimage"},"image":{"@id":"https:\/\/www.primecursos.com.br\/blog\/apoiando-filhos-estudos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.primecursos.com.br\/blog\/wp-content\/uploads\/2015\/03\/Pais-apoiando-educa\u00e7\u00e3o.jpg","datePublished":"2015-03-13T08:00:17+00:00","description":"Aprenda qual a melhor maneira de ajudar os filhos nos estudos, trazendo mais benef\u00edcios para o aprendizado das crian\u00e7as.","breadcrumb":{"@id":"https:\/\/www.primecursos.com.br\/blog\/apoiando-filhos-estudos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.primecursos.com.br\/blog\/apoiando-filhos-estudos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.primecursos.com.br\/blog\/apoiando-filhos-estudos\/#primaryimage","url":"https:\/\/www.primecursos.com.br\/blog\/wp-content\/uploads\/2015\/03\/Pais-apoiando-educa\u00e7\u00e3o.jpg","contentUrl":"https:\/\/www.primecursos.com.br\/blog\/wp-content\/uploads\/2015\/03\/Pais-apoiando-educa\u00e7\u00e3o.jpg","width":1024,"height":539,"caption":"Pais apoiando educa\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/www.primecursos.com.br\/blog\/apoiando-filhos-estudos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.primecursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Apoiando os filhos nos estudos"}]},{"@type":"WebSite","@id":"https:\/\/www.primecursos.com.br\/blog\/#website","url":"https:\/\/www.primecursos.com.br\/blog\/","name":"Prime Cursos","description":"Cursos gr\u00e1tis com certificado v\u00e1lido","publisher":{"@id":"https:\/\/www.primecursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.primecursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.primecursos.com.br\/blog\/#organization","name":"Prime Cursos Online","url":"https:\/\/www.primecursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.primecursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.primecursos.com.br\/blog\/wp-content\/uploads\/2018\/03\/prime-cursos-gratis-online-logo-070318b-1.png","contentUrl":"https:\/\/www.primecursos.com.br\/blog\/wp-content\/uploads\/2018\/03\/prime-cursos-gratis-online-logo-070318b-1.png","width":330,"height":80,"caption":"Prime Cursos Online"},"image":{"@id":"https:\/\/www.primecursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/primecursos\/","https:\/\/x.com\/primecursosbr"]},{"@type":"Person","@id":"https:\/\/www.primecursos.com.br\/blog\/#\/schema\/person\/f75c3b4178ad1d2652ae372dc8284315","name":"Bruno West","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3f4e7619846fa72d0a5106c7aebfc167807a00ac75982cb190722ab0a20b290b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3f4e7619846fa72d0a5106c7aebfc167807a00ac75982cb190722ab0a20b290b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3f4e7619846fa72d0a5106c7aebfc167807a00ac75982cb190722ab0a20b290b?s=96&d=mm&r=g","caption":"Bruno West"},"sameAs":["http:\/\/www.primecursos.com.br"],"url":"https:\/\/www.primecursos.com.br\/blog\/author\/bruno\/"}]}},"taxonomy_info":{"post_tag":[{"value":13,"label":"Estudos"}]},"featured_image_src_large":["https:\/\/www.primecursos.com.br\/blog\/wp-content\/uploads\/2015\/03\/Pais-apoiando-educa\u00e7\u00e3o-1024x539.jpg",1024,539,true],"author_info":{"display_name":"Bruno West","author_link":"https:\/\/www.primecursos.com.br\/blog\/author\/bruno\/"},"comment_info":3,"category_info":[],"tag_info":[{"term_id":13,"name":"Estudos","slug":"estudos","term_group":0,"term_taxonomy_id":13,"taxonomy":"post_tag","description":"","parent":0,"count":84,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/www.primecursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.primecursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.primecursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.primecursos.com.br\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.primecursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1650"}],"version-history":[{"count":0,"href":"https:\/\/www.primecursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1650\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.primecursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1653"}],"wp:attachment":[{"href":"https:\/\/www.primecursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.primecursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.primecursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}